{"id":1,"count":8,"description":"","link":"https:\/\/preview.vwthemesdemo.com\/vw-one-page-pro\/category\/uncategorized\/","name":"Uncategorized","slug":"uncategorized","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/preview.vwthemesdemo.com\/vw-one-page-pro\/wp-json\/wp\/v2\/categories\/1","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/preview.vwthemesdemo.com\/vw-one-page-pro\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/preview.vwthemesdemo.com\/vw-one-page-pro\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/preview.vwthemesdemo.com\/vw-one-page-pro\/wp-json\/wp\/v2\/posts?categories=1"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}