{"id":45,"count":1,"description":"This is sample Post category","link":"https:\/\/preview.vwthemesdemo.com\/vw-business-lounge\/category\/networking\/","name":"Networking","slug":"networking","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/preview.vwthemesdemo.com\/vw-business-lounge\/wp-json\/wp\/v2\/categories\/45","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/preview.vwthemesdemo.com\/vw-business-lounge\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/preview.vwthemesdemo.com\/vw-business-lounge\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/preview.vwthemesdemo.com\/vw-business-lounge\/wp-json\/wp\/v2\/posts?categories=45"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}